{"text_format":"1","workbook":"xlsx","n_sheets":9,"sheets":["Checklist","Front Page","Lunch","LP","Services","Prime Promo","Data","Test","TEST 2"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":1,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Checklist","index":0,"n_rows":98,"n_cols":10,"rows_kept":98,"cut":false,"hidden":false,"merged":[[90,0,90,4],[36,0,36,4],[45,0,45,4],[54,0,54,4],[63,0,63,4],[72,0,72,4],[81,0,81,4]]}
[]
[]
[]
[null,null,null,"Store Format","SOTF"]
[]
[]
[null,null,null,null,null,null,null,null,null,{"$f":"VLOOKUP(H6,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[null,"All Checked",{"$f":"VLOOKUP('Front Page'!B698,'Front Page'!B:B,1,FALSE)","v":"Yes"},null,null,null,null,"Yes",null,{"$error":"#N/A"}]
[null,null,null,null,null,null,null,"Yes",null,"Yes"]
[null,null,null,null,null,null,null,"Yes",null,{"$f":"VLOOKUP(H9,$C$8,1,FALSE)","v":"Yes"}]
[null,null,null,null,null,null,null,null,null,"Yes"]
[null,null,null,null,null,null,null,null,null,{"$error":"#N/A"}]
[null,null,null,null,null,null,null,null,null,{"$error":"#N/A"}]
[null,null,null,null,null,null,null,null,null,{"$error":"#N/A"}]
[null,null,null,null,null,null,null,null,null,{"$error":"#N/A"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B298,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B498,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B698,$C$8,1,FALSE)","v":"Yes"}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B898,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1098,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B700,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B307,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B507,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B707,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B907,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1107,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B709,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B316,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B516,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B716,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B916,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1116,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B718,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B325,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B525,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B725,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B925,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1125,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B727,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B334,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B534,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B734,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B934,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1134,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B736,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B343,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B543,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B743,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B943,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1143,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B745,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Checks"]
["Beauty ",{"$f":"VLOOKUP('Front Page'!B352,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Toils",{"$f":"VLOOKUP('Front Page'!B552,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Seasonal",{"$f":"VLOOKUP('Front Page'!B752,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Healthcare",{"$f":"VLOOKUP('Front Page'!B952,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
["Salesplan",{"$f":"VLOOKUP('Front Page'!B1152,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]
[]
["Final",{"$f":"VLOOKUP('Front Page'!B754,$C$8,1,FALSE)","v":{"$error":"#N/A"}}]

{"sheet":"Front Page","index":1,"n_rows":1300,"n_cols":20,"rows_kept":1300,"cut":false,"hidden":false,"merged":[[899,0,899,9],[1099,0,1099,9],[1299,0,1299,9],[0,19,0,25],[0,0,0,9],[99,0,99,9],[299,0,299,9],[499,0,499,9],[699,0,699,9],[122,0,122,9],[140,0,140,9],[152,0,152,9],[172,0,172,9],[182,0,182,9]]}
["Standards & Guidance Workbook",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"In All"]
[]
[]
["Please select the store format",null,null,null,"London"]
[]
[]
[]
[]
["Please select the category"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Standard"]
[]
["Tills "]
["Service box",null,"Inexact (where to get them from if they don’t have one",null,null,null,null,null,"SAG Size Etc"]
[]
["Checks","Highlight checks",null,"Comparision Reports",null,"General Checks"]
[]
["Security Cladding"]
[]
["Discontinued POGS?"]
[]
["POG's with power"]
[]
[]
["Fixtures","G00255 = Wide\nG00255 G00256 = 3 Way\nG00274 = Narrow","List of all the random old fixture codes Eg. Fix 381"]
[]
[]
[]
[]
[]
[]
[]
[]
["Seasonal"]
[]
["Baby"]
[]
["Photo"]
[]
["Lunch"]
[]
["Sun"]
[]
["Christmas "]
[]
["Gift"]
[]
["Toys"]
[]
[]
[]
["Toiletries "]
[]
["Hair"]
[]
["Washing & Bathing"]
[]
["Mens"]
[]
["Personal Care"]
[]
[]
[]
["Beauty"]
[]
["Accessories "]
[]
["EB"]
[]
["Fragrance"]
[]
["Make-up"]
[]
["No7"]
[]
["Premium"]
[]
["Skincare"]
[]
["Beauty Re-invention "]
[]
[]
[]
["Healthcare"]
[]
["Chemist"]
[]
["Medicines"]
[]
["Lifestyle medicines"]
[]
[]
[]
["Salesplan"]
[]
["FSDUs"]
[]
["Ends"]
[]
["Fragrance"]
[]
["IQM"]
[]
["Prime Promotion "]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["London"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Scotland"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Are you done?","Yes"]
[]
["ROI"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["YLBP"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["LP"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Services"]

{"sheet":"Lunch","index":2,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"LP","index":3,"n_rows":346,"n_cols":8,"rows_kept":346,"cut":false,"hidden":false,"merged":[[0,0,0,7]]}
["LP Extract"]
["Name","Fitting Type","Build Size","Status","Planogram ID","DBKey","Old POG ID","Date Live"]
["#Giftcard A & Bag for life Excl Itunes LP (Waitrose)","N/A","N/A","Live",252091,634698,252091,"2016-11-16"]
["Dental 200mm 0.5G LP Trial GLF","G",0.5,"Live",396966,798452,396966,"2019-10-28"]
["Dental 200mm 0.5W LP Trial GLF","W",0.5,"Live",396653,798451,396653,"2019-10-28"]
["Dental 200mm 1.0G LP Trial GLF","G",1,"Live",381794,798449,381794,"2019-10-28"]
["Dental 200mm 1.0W LP Trial GLF","W",1,"Live",383876,798443,383876,"2019-10-28"]
["Dental 200mm 1.0Z Ladder LP Trial GLF","Z",1,"Live",388153,798450,388153,"2019-10-28"]
["Dental 200mm 2.0W LP Trial GLF","W",2,"Live",394070,798440,394070,"2019-10-28"]
["Dental 200mm 3.0G LP Trial GLF","G",3,"Live",394299,798437,394299,"2019-10-28"]
["Dental 200mm 3.0W LP Trial GLF","W",3,"Live",397802,798439,397802,"2019-10-28"]
["Dental 200mm LP Trial 4.0G GLF","G",4,"Live",397803,798434,397803,"2019-10-28"]
["Dental 300mm 1.0G LP Trial GLF","G",1,"Live",384694,798447,384694,"2019-10-28"]
["Dental 300mm 1.0W LP Trial GLF","W",1,"Live",530632,798445,530632,"2019-10-28"]
["LP Baby Composite 300mm 1.0W GLF","W",1,"Live",408399,798716,408399,"2019-10-14"]
["LP Baby Composite 300mm 1.5G GLF","G",1.5,"Live",408400,798717,408400,"2019-10-14"]
["LP Baby Composite 300mm 1.5W GLF","W",1.5,"Live",394842,798705,394842,"2019-10-14"]
["LP Baby Composite 300mm 10.0W GLF","W",10,"Live",394022,798701,394022,"2019-10-14"]
["LP Baby Composite 300mm 10.5W GLF","W",10.5,"Live",395400,798708,395400,"2019-10-14"]
["LP Baby Composite 300mm 11.0W GLF","W",11,"Live",395401,798709,395401,"2019-10-14"]
["LP Baby Composite 300mm 2.0G GLF","G",2,"Live",394924,798706,394924,"2019-10-14"]
["LP Baby Composite 300mm 2.0W GLF","W",2,"Live",387160,798692,387160,"2019-10-14"]
["LP Baby Composite 300mm 2.0W Hospital Inc Drawer Line GLF","W",2,"Live",426353,798719,426353,"2019-10-14"]
["LP Baby Composite 300mm 2.5G GLF","G",2.5,"Live",389036,798694,389036,"2019-10-14"]
["LP Baby Composite 300mm 2.5W GLF","W",2.5,"Live",395403,798710,395403,"2019-10-14"]
["LP Baby Composite 300mm 3.0G GLF","G",3,"Live",395392,798707,395392,"2019-10-14"]
["LP Baby Composite 300mm 3.0W GLF","W",3,"Live",393332,798695,393332,"2019-10-14"]
["LP Baby Composite 300mm 3.5G GLF","G",3.5,"Live",393477,798700,393477,"2019-10-14"]
["LP Baby Composite 300mm 4.0W GLF","W",4,"Live",383757,798689,383757,"2019-10-14"]
["LP Baby Composite 300mm 5.0W GLF","W",5,"Live",381645,798681,381645,"2019-10-14"]
["LP Baby Composite 300mm 5.5W GLF","W",5.5,"Live",393333,798696,393333,"2019-10-14"]
["LP Baby Composite 300mm 6.0W GLF","W",6,"Live",388412,798693,388412,"2019-10-14"]
["LP Baby Composite 300mm 7.0G GLF","G",7,"Live",394770,798704,394770,"2019-10-14"]
["LP Baby Composite 300mm 7.0W GLF","W",7,"Live",396058,798711,396058,"2019-10-14"]
["LP Baby Composite 300mm 7.5W GLF","W",7.5,"Live",393386,798697,393386,"2019-10-14"]
["LP Baby Composite 300mm 8.0W GLF","W",8,"Live",393438,798699,393438,"2019-10-14"]
["LP Baby Composite 300mm 8.5W GLF","W",8.5,"Live",393434,798698,393434,"2019-10-14"]
["LP Baby Composite 300mm 9.5W GLF","W",9.5,"Live",394048,798703,394048,"2019-10-14"]
["LP Baby Composite Hospital Drawer Line","G",1,"Live",426671,798720,426671,"2019-10-14"]
["LP Baby Toiletries Lifestyle Composite 200mm 0.5G GLF","G",0.5,"Live",396416,796947,396416,"2019-10-14"]
["LP Baby Toiletries Lifestyle Composite 200mm 1.0W GLF","W",1,"Live",396565,805960,396565,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 1.5W GLF","W",1.5,"Live",395330,805959,395330,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 2.0G GLF","G",2,"Live",396715,805955,396715,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 2.0W GLF","W",2,"Live",396420,805953,396420,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 2.5W GLF","W",2.5,"Live",396708,805952,396708,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 3.0W GLF","W",3,"Live",397243,805951,397243,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 3.5G GLF","G",3.5,"Live",396390,805950,396390,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 3.5W GLF","W",3.5,"Live",396706,805949,396706,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 200mm 4.0W GLF","W",4,"Live",396431,805946,396431,"2019-10-28"]
["LP Baby Toiletries Lifestyle Composite 400mm 3.0G GLF","G",3,"Live",775229,796941,775229,"2019-10-14"]
["LP Chemist And Complementary Health Composite 200mm 1.0W GLF","W",1,"Live",431824,734130,431824,"2019-01-07"]
["LP Chemist And Complementary Health Composite 200mm 1.5G GLF","G",1.5,"Live",431827,734129,431827,"2019-01-07"]
["LP Chemist And Complementary Health Composite 200mm 1.5W GLF","W",1.5,"Live",431815,734128,431815,"2019-01-07"]
["LP Chemist And Complementary Health Composite 200mm 2.0W GLF","W",2,"Live",396605,734126,396605,"2019-01-07"]
["LP Chemist And Complementary Health Composite 200mm 2.5G GLF","G",2.5,"Live",396578,734125,396578,"2019-01-07"]
["LP Chemist And Complementary Health Composite 200mm 3.0G GLF","G",3,"Live",431803,734124,431803,"2019-01-07"]
["LP Chemist And Complementary Health Composite 200mm 3.0W GLF","W",3,"Live",397019,734123,397019,"2019-01-07"]
["LP Chemist Composite 200mm 2.0W GLF","W",2,"Live",389030,758888,389030,"2019-02-04"]
["LP Chemist Composite 200mm 2.5G GLF","G",2.5,"Live",389035,758887,389035,"2019-02-04"]
["LP Chemist Composite 200mm 2.5W GLF","W",2.5,"Live",390465,758886,390465,"2019-02-04"]
["LP Chemist Composite 200mm 3.0G GLF","G",3,"Live",384138,758885,384138,"2019-02-04"]
["LP Chemist Composite 200mm 3.0W GLF","W",3,"Live",381643,758884,381643,"2019-02-04"]
["LP Chemist Composite 200mm 3.5G GLF","G",3.5,"Live",393787,758883,393787,"2019-02-04"]
["LP Chemist Composite 200mm 3.5W GLF","W",3.5,"Live",393331,758882,393331,"2019-02-04"]
["LP Chemist Composite 200mm 4.0G GLF","G",4,"Live",390681,758881,390681,"2019-02-04"]
["LP Chemist Composite 200mm 4.0W GLF","W",4,"Live",393330,758880,393330,"2019-02-04"]
["LP Chemist Composite 200mm 5.0G GLF","G",5,"Live",394490,758879,394490,"2019-02-04"]
["LP Chemist Composite 200mm 5.0W GLF","W",5,"Live",397751,758877,397751,"2019-02-04"]
["LP Chemist Composite 200mm 5.5G GLF","G",5.5,"Live",394558,758876,394558,"2019-02-04"]
["LP Chemist Composite 200mm 6.0G GLF","G",6,"Live",394586,758875,394586,"2019-02-04"]
["LP Chemist Composite 200mm 7.0G GLF","G",7,"Live",397752,758871,397752,"2019-02-04"]
["LP Complementary Health Composite 200mm 0.5W GLF","W",0.5,"Live",431674,769161,431674,"2019-09-16"]
["LP Complementary Health Composite 200mm 1.0G GLF","G",1,"Live",386294,769145,386294,"2019-09-16"]
["LP Complementary Health Composite 200mm 1.0W GLF","W",1,"Live",388966,769146,388966,"2019-09-16"]
["LP Complementary Health Composite 200mm 1.5G GLF","G",1.5,"Live",394804,769151,394804,"2019-09-16"]
["LP Complementary Health Composite 200mm 1.5W GLF","W",1.5,"Live",390551,769147,390551,"2019-09-16"]
["LP Complementary Health Composite 200mm 2.0G GLF","G",2,"Live",384745,769144,384745,"2019-09-16"]
["LP Complementary Health Composite 200mm 2.0W GLF","W",2,"Live",431689,769162,431689,"2019-09-16"]
["LP Complementary Health Composite 200mm 2.5G GLF","G",2.5,"Live",431690,769163,431690,"2019-09-16"]
["LP Complementary Health Composite 200mm 2.5W GLF","W",2.5,"Live",393161,769150,393161,"2019-09-16"]
["LP Complementary Health Composite 200mm 3.0G GLF","G",3,"Live",381731,769142,381731,"2019-09-16"]
["LP Complementary Health Composite 200mm 3.0W GLF","W",3,"Live",384243,769143,384243,"2019-09-16"]
["LP Complementary Health Composite 200mm 3.5G GLF","G",3.5,"Live",395390,769155,395390,"2019-09-16"]
["LP Complementary Health Composite 200mm 3.5W GLF","W",3.5,"Live",392995,769148,392995,"2019-09-16"]
["LP Complementary Health Composite 200mm 4.0G GLF","G",4,"Live",396063,769157,396063,"2019-09-16"]
["LP Complementary Health Composite 200mm 4.0W GLF","W",4,"Live",393021,769149,393021,"2019-09-16"]
["LP Complementary Health Composite 200mm 4.5G GLF","G",4.5,"Live",394817,769152,394817,"2019-09-16"]
["LP Complementary Health Composite 200mm 5.0W GLF","W",5,"Live",395754,769156,395754,"2019-09-16"]
["LP Complementary Health Composite 200mm 5.5G GLF","G",5.5,"Live",394818,769153,394818,"2019-09-16"]
["LP Complementary Health Composite 200mm 6.0G GLF","G",6,"Live",394819,769154,394819,"2019-09-16"]
["LP Complementary Health Composite 200mm 6.0W GLF","W",6,"Live",409571,769160,409571,"2019-09-16"]
["LP Complementary Health Composite 200mm 7.0G GLF","G",7,"Live",397889,769159,397889,"2019-09-16"]
["LP Complementary Health Composite 200mm 8.0G GLF","G",8,"Live",397887,769158,397887,"2019-09-16"]
["LP Counter Top Unit 1 GLF","Z",1,"Live",382911,774107,382911,"2019-05-06"]
["LP Counter Top Unit 2 GLF","Z",1,"Live",382912,391935,382912,"2012-08-25"]
["LP Haircare Composite 200mm 10.0G GLF","G",10,"Live",428436,804386,428436,"2019-10-14"]
["LP Haircare Composite 200mm 10.0W GLF","W",10,"Live",394166,804535,394166,"2019-10-14"]
["LP Haircare Composite 200mm 11.0G GLF","G",11,"Live",394069,804534,394069,"2019-10-14"]
["LP Haircare Composite 200mm 12.0G GLF","G",12,"Live",394172,804385,394172,"2019-10-14"]
["LP Haircare Composite 200mm 12.0G GLF","G",12,"Live",771227,771227,771227,"2019-07-22"]
["LP Haircare Composite 200mm 2.0W GLF","W",2,"Live",389037,793279,389037,"2019-07-22"]
["LP Haircare Composite 200mm 2.5G GLF","G",2.5,"Live",389451,793281,389451,"2019-07-22"]
["LP Haircare Composite 200mm 2.5W GLF","W",2.5,"Live",387562,804550,387562,"2019-10-14"]
["LP Haircare Composite 200mm 3.0W GLF","W",3,"Live",384906,804549,384906,"2019-10-14"]
["LP Haircare Composite 200mm 4.0G GLF","G",4,"Live",381475,804398,381475,"2019-10-14"]
["LP Haircare Composite 200mm 4.0W GLF","W",4,"Live",392263,804547,392263,"2019-10-14"]
["LP Haircare Composite 200mm 5.0G GLF","G",5,"Live",392278,804395,392278,"2019-10-14"]
["LP Haircare Composite 200mm 5.0W GLF","W",5,"Live",392292,804546,392292,"2019-10-14"]
["LP Haircare Composite 200mm 5.5G GLF","G",5.5,"Live",395850,804545,395850,"2019-10-14"]
["LP Haircare Composite 200mm 5.5W GLF","W",5.5,"Live",395009,804544,395009,"2019-10-14"]
["LP Haircare Composite 200mm 6.0G GLF","G",6,"Live",428432,804543,428432,"2019-10-14"]
["LP Haircare Composite 200mm 6.0W GLF","W",6,"Live",393970,804542,393970,"2019-10-14"]
["LP Haircare Composite 200mm 6.5G GLF","G",6.5,"Live",392403,804541,392403,"2019-10-14"]
["LP Haircare Composite 200mm 6.5W GLF","W",6.5,"Live",428398,804540,428398,"2019-10-14"]
["LP Haircare Composite 200mm 7.0G GLF","G",7,"Live",395012,804539,395012,"2019-10-14"]
["LP Haircare Composite 200mm 8.0G GLF","G",8,"Live",428399,804538,428399,"2019-10-14"]
["LP Haircare Composite 200mm 8.0W GLF","W",8,"Live",428418,804537,428418,"2019-10-14"]
["LP Haircare Composite 200mm 9.0G GLF","G",9,"Live",428431,804536,428431,"2019-10-14"]
["LP Haircare Mens Composite 200mm 0.5W GLF","W",0.5,"Live",397224,804364,397224,"2019-10-14"]
["LP Haircare Mens Composite 200mm 1.0G GLF","G",1,"Live",396566,804363,396566,"2019-10-14"]
["LP Haircare Mens Composite 200mm 1.0W GLF","W",1,"Live",396575,804362,396575,"2019-10-14"]
["LP Haircare Mens Composite 200mm 1.5G GLF","G",1.5,"Live",397093,804361,397093,"2019-10-14"]
["LP Haircare Mens Composite 200mm 2.0W GLF","W",2,"Live",410774,804360,410774,"2019-10-14"]
["LP Haircare Mens Composite 200mm 2.5G GLF","G",2.5,"Live",410890,804359,410890,"2019-10-14"]
["LP Haircare Mens Composite 200mm 2.5W GLF","W",2.5,"Live",397164,804358,397164,"2019-10-14"]
["LP Haircare Mens Composite 200mm 3.0G GLF","G",3,"Live",397166,804357,397166,"2019-10-14"]
["LP Healthcare Composite 200mm 1.0W GLF","W",1,"Live",395371,759807,395371,"2019-02-04"]
["LP Healthcare Composite 200mm 2.0G GLF","G",2,"Live",396695,759805,396695,"2019-02-04"]
["LP Healthcare Composite 200mm 2.0W GLF","W",2,"Live",396679,759804,396679,"2019-02-04"]
["LP Healthcare Composite 200mm 2.5W GLF","W",2.5,"Live",396678,759803,396678,"2019-02-04"]
["LP Healthcare Composite 200mm 3.0G GLF","G",3,"Live",396693,759802,396693,"2019-02-04"]
["LP Healthcare Composite 200mm 3.0W GLF","W",3,"Live",396677,759800,396677,"2019-02-04"]
["LP Healthcare Composite 200mm 3.5W GLF","W",3.5,"Live",396676,759799,396676,"2019-02-04"]
["LP Healthcare Composite 200mm 4.0G GLF","G",4,"Live",396691,759798,396691,"2019-02-04"]
["LP Healthcare Composite 200mm 4.0W GLF","W",4,"Live",396675,759796,396675,"2019-02-04"]
["LP Healthcare Composite 200mm 4.5G GLF","G",4.5,"Live",396690,759795,396690,"2019-02-04"]
["LP Healthcare Composite 200mm 4.5W GLF","W",4.5,"Live",396674,759794,396674,"2019-02-04"]
["LP Healthcare Composite 200mm 5.0G GLF","G",5,"Live",396689,759793,396689,"2019-02-04"]
["LP Healthcare Composite 200mm 5.0W GLF","W",5,"Live",396673,758904,396673,"2019-02-04"]
["LP Healthcare Composite 400mm 2.0G GLF","G",2,"Live",561380,759806,561380,"2019-02-04"]
["LP Healthy Heart Composite 400mm 3.0G GLF","G",3,"Live",338131,774071,338131,"2019-05-06"]
["LP Healthy Heart Composite 400mm 4.0G GLF","G",4,"Live",338139,774074,338139,"2019-05-06"]
["LP Healthy Heart Composite 400mm 4.0W GLF","W",4,"Live",338145,774077,338145,"2019-05-06"]
["LP Hosiery 200mm 0.5G GLF","G",0.5,"Live",429433,780830,429433,"2019-07-19"]
["LP Hosiery 200mm 0.5W GLF","W",0.5,"Live",429369,780804,429369,"2019-07-19"]
["LP Hosiery 200mm 0.5Z Ladder GLF","Z",0.5,"Live",438382,780847,438382,"2019-07-19"]
["LP Hosiery 200mm 2 Shelf GLF","W",2,"Live",382531,780805,382531,"2019-07-19"]
["LP Hosiery Narrow End 1.0G GLF","E",1,"Live",387329,780829,387329,"2019-07-19"]
["LP Incontinence 300mm 0.5G GLF","G",0.5,"Live",431652,806861,431652,"2019-11-11"]
["LP Incontinence 300mm 0.5W GLF","W",0.5,"Live",431651,806862,431651,"2019-11-11"]
["LP Incontinence 300mm 1.0G GLF","G",1,"Live",381734,806863,381734,"2019-11-11"]
["LP Incontinence 300mm 1.0W GLF","W",1,"Live",383884,806864,383884,"2019-11-11"]
["LP Incontinence 300mm 1.5G GLF","G",1.5,"Live",393351,806860,393351,"2019-11-11"]
["LP Incontinence 300mm 1.5W GLF","W",1,"Live",393355,806865,393355,"2019-11-11"]
["LP Incontinence 300mm 2.0G GLF","G",2,"Live",394681,806866,394681,"2019-11-11"]
["LP Independent Living Composite 200mm 3.0G GLF","G",3,"Live",334145,649988,334145,"2017-04-17"]
["LP Independent Living Composite 300mm 2.0G GLF","G",2,"Live",338262,649989,338262,"2017-04-17"]
["LP Independent Living Composite 300mm 2.0W GLF","W",2,"Live",338263,649991,338263,"2017-04-17"]
["LP Independent Living Composite 400mm 2.0G GLF","G",2,"Live",338223,649990,338223,"2017-04-17"]
["LP Independent Living Composite 400mm 2.0W GLF","W",2,"Live",338264,649993,338264,"2017-04-17"]
["LP Independent Living Composite 400mm 3.0W GLF","W",3,"Live",338265,649992,338265,"2017-04-17"]
["LP Medicines Composite 200mm 2.0W GLF","W",2,"Live",387991,760519,387991,"2019-02-04"]
["LP Medicines Composite 200mm 2.5G GLF","G",2.5,"Live",392699,760518,392699,"2019-02-04"]
["LP Medicines Composite 200mm 2.5W GLF","W",2.5,"Live",431663,760517,431663,"2019-02-04"]
["LP Medicines Composite 200mm 3.0G GLF","G",3,"Live",431668,760516,431668,"2019-02-04"]
["LP Medicines Composite 200mm 3.0W GLF","W",3,"Live",578776,760515,578776,"2019-02-04"]
["LP Medicines Composite 200mm 3.0W GLF - 1","W",3,"Live",390349,760514,390349,"2019-02-04"]
["LP Medicines Composite 200mm 4.0G GLF","G",4,"Live",394440,760513,394440,"2019-02-04"]
["LP Medicines Composite 200mm 4.0W GLF","W",4,"Live",381696,796238,381696,"2019-07-29"]
["LP Medicines Composite 200mm 4.5W GLF","W",4.5,"Live",392259,796239,392259,"2019-07-29"]
["LP Medicines Composite 200mm 5.0G GLF","G",5,"Live",384434,796240,384434,"2019-07-29"]
["LP Medicines Composite 200mm 5.0W GLF","W",5,"Live",384295,796241,384295,"2019-07-29"]
["LP Medicines Composite 200mm 5.5W GLF","W",5.5,"Live",392674,796242,392674,"2019-07-29"]
["LP Medicines Composite 200mm 6.0G GLF","G",6,"Live",394444,796243,394444,"2019-07-29"]
["LP Medicines Composite 200mm 6.0W GLF","W",6,"Live",392677,796244,392677,"2019-07-29"]
["LP Medicines Composite 200mm 6.5G GLF","G",6.5,"Live",394456,796245,394456,"2019-07-29"]
["LP Medicines Composite 200mm 7.0G GLF","G",7,"Live",394473,796246,394473,"2019-07-29"]
["LP Medicines Composite 200mm 8.0G GLF","G",8,"Live",397750,796247,397750,"2019-07-29"]
["LP Mens Composite 200mm 0.5G GLF","G",0.5,"Live",389057,812411,389057,"2019-10-28"]
["LP Mens Composite 200mm 1.0G GLF","G",1,"Live",384014,812413,384014,"2019-10-28"]
["LP Mens Composite 200mm 1.0W GLF","W",1,"Live",381733,812412,381733,"2019-10-28"]
["LP Mens Composite 200mm 1.5G GLF","G",1.5,"Live",393538,812415,393538,"2019-10-28"]
["LP Mens Composite 200mm 1.5W GLF","W",1.5,"Live",391636,812414,391636,"2019-10-28"]
["LP Mens Composite 200mm 2.0G GLF","G",2,"Live",391659,812417,391659,"2019-10-28"]
["LP Mens Composite 200mm 2.0W GLF","W",2,"Live",394198,812416,394198,"2019-10-28"]
["LP Mens Composite 200mm 2.5G GLF","G",2.5,"Live",394218,812418,394218,"2019-10-28"]
["LP Mens Composite 200mm 3.0G GLF","G",3,"Live",394236,812420,394236,"2019-10-28"]
["LP Mens Composite 200mm 3.0W GLF","W",3,"Live",397817,812419,397817,"2019-10-28"]
["LP Mens Composite 200mm 4.0G GLF","G",4,"Live",397816,812421,397816,"2019-10-28"]
["LP Seasonal End 1 1.0Y Narrow","Y",1,"Live",659557,660159,659557,"2017-05-10"]
["LP Seasonal End 1 1.0Y Narrow ROI","Y",1,"Live",659556,660161,659556,"2017-05-10"]
["LP Seasonal End 1 1.0Y Standard","Y",1,"Live",659554,660160,659554,"2017-05-10"]
["LP Skincare Composite 200mm 10.0G GLF","G",10,"Live",393968,808916,393968,"2019-10-14"]
["LP Skincare Composite 200mm 2.0W GLF","W",2,"Live",394932,808989,394932,"2019-10-14"]
["LP Skincare Composite 200mm 2.5W GLF","W",2.5,"Live",381648,808987,381648,"2019-10-14"]
["LP Skincare Composite 200mm 3.0G GLF","G",3,"Live",395344,808985,395344,"2019-10-14"]
["LP Skincare Composite 200mm 3.0W GLF","W",3,"Live",384773,808980,384773,"2019-10-14"]
["LP Skincare Composite 200mm 3.5G GLF","G",3.5,"Live",391584,808977,391584,"2019-10-14"]
["LP Skincare Composite 200mm 3.5W GLF","W",3.5,"Live",383754,808969,383754,"2019-10-14"]
["LP Skincare Composite 200mm 4.0W GLF","W",4,"Live",392432,808966,392432,"2019-10-14"]
["LP Skincare Composite 200mm 4.5G GLF","G",4.5,"Live",390189,808963,390189,"2019-10-14"]
["LP Skincare Composite 200mm 4.5W GLF","W",4.5,"Live",392490,808961,392490,"2019-10-14"]
["LP Skincare Composite 200mm 5.0W GLF","W",5,"Live",392535,808959,392535,"2019-10-14"]
["LP Skincare Composite 200mm 5.5G GLF","G",5.5,"Live",395414,808956,395414,"2019-10-14"]
["LP Skincare Composite 200mm 6.0G GLF","G",6,"Live",392503,808953,392503,"2019-10-14"]
["LP Skincare Composite 200mm 6.0W GLF","W",6,"Live",392685,808950,392685,"2019-10-14"]
["LP Skincare Composite 200mm 6.5G GLF","G",6.5,"Live",392624,808949,392624,"2019-10-14"]
["LP Skincare Composite 200mm 7.0G GLF","G",7,"Live",395015,808947,395015,"2019-10-14"]
["LP Skincare Composite 200mm 7.0W GLF","W",7,"Live",393927,808945,393927,"2019-10-14"]
["LP Skincare Composite 200mm 7.5G GLF","G",7.5,"Live",392858,808943,392858,"2019-10-14"]
["LP Skincare Composite 200mm 7.5W GLF","W",7.5,"Live",395870,808940,395870,"2019-10-14"]
["LP Skincare Composite 200mm 8.0G GLF","G",8,"Live",395016,808938,395016,"2019-10-14"]
["LP Skincare Composite 200mm 9.0G GLF","G",9,"Live",395883,808936,395883,"2019-10-14"]
["LP Skincare Composite 200mm 9.0W GLF","W",9,"Live",396590,808935,396590,"2019-10-14"]
["LP Skincare Incl Hosiery Composite 200mm 11.0W GLF","W",11,"Live",397210,809017,397210,"2019-10-14"]
["LP Skincare Incl Hosiery Composite 200mm 12.0G GLF","G",12,"Live",397807,809013,397807,"2019-10-14"]
["LP Skincare Incl Tissues Composite 200mm 2.0W GLF","W",2,"Live",397800,809008,397800,"2019-10-14"]
["LP Skincare Incl Tissues Composite 200mm 3.0G GLF","G",3,"Live",397801,809004,397801,"2019-10-14"]
["LP Skincare Incl Tissues Composite 200mm 3.0W GLF","W",3,"Live",393866,809000,393866,"2019-10-14"]
["LP Skincare Incl Tissues Composite 200mm 4.0G GLF","G",4,"Live",395279,808995,395279,"2019-10-14"]
["LP Snacking And Photo Composite 200mm 0.5G GLF","G",0.5,"Live",397734,793602,397734,"2019-10-07"]
["LP Snacking And Photo Composite 200mm 0.5W GLF","W",0.5,"Live",397910,793603,397910,"2019-10-07"]
["LP Snacking And Photo Composite 200mm 1.0E GLF","E",1,"Live",382669,793611,382669,"2019-10-07"]
["LP Snacking And Photo Composite 200mm 1.0G GLF","G",1,"Live",383868,793598,383868,"2019-10-07"]
["LP Snacking And Photo Composite 200mm 1.0W GLF","W",1,"Live",394823,793599,394823,"2019-10-07"]
["LP Snacking And Photo Composite 200mm 1.5G GLF","G",1.5,"Live",394470,793597,394470,"2019-10-07"]
["LP Snacking And Photo Composite Ladder 200mm 0.5Z","Z",0.5,"Live",438384,793609,438384,"2019-10-07"]
["LP Snacking And Photo Composite Ladder 200mm 1.0Z","Z",1,"Live",395412,793600,395412,"2019-10-07"]
["LP Sun & Self Tan 200mm 1.0G GF","G",1,"Live",383870,774181,383870,"2019-05-06"]
["LP Sun & Self Tan 200mm 1.0W GF","W",1,"Live",382526,774182,382526,"2019-05-06"]
["LP Sun & Self Tan 200mm 1.0Z Ladder GLF","Z",1,"Live",396021,774183,396021,"2019-05-06"]
["LP Toiletries End 1 1.0Y Narrow","Y",1,"Live",405531,701063,405531,"2017-12-15"]
["LP Toiletries Lifestyle Hospital Composite 200mm 1.0W GLF","W",1,"Live",426830,805971,426830,"2019-10-28"]
["LP Toiletries Value Promotional Site 200mm 2.0G GLF","G",2,"Live",658521,811059,658521,"2019-12-04"]
["LP Toiletries Value Promotional Site 400mm 2.0G GLF","G",2,"Live",658535,811060,658535,"2019-12-04"]
["LP Toiletries Value Promotional Site 400mm 2.0W GLF","W",2,"Live",658538,811061,658538,"2019-12-04"]
["LP Value End 200mm 1 1.0Y Narrow","E",1,"Live",717926,806531,717926,"2019-10-23"]
["LP Value End 200mm 1 1.0Y Standard","E",1,"Live",717901,806532,717901,"2019-10-23"]
["LP Value End 200mm 2 1.0Y Narrow","E",1,"Live",717927,800455,717927,"2019-09-11"]
["LP Value End 200mm 2 1.0Y Standard","E",1,"Live",717918,800471,717918,"2019-09-11"]
["LP Value End 200mm 3 1.0Y Narrow","E",1,"Live",717928,806533,717928,"2019-10-23"]
["LP Value End 200mm 3 1.0Y Standard","E",1,"Live",717923,806534,717923,"2019-10-23"]
["LP Value End 200mm 4 1.0Y Narrow","E",1,"Live",717929,804460,717929,"2019-10-09"]
["LP Value End 200mm 4 1.0Y Standard","E",1,"Live",717925,804462,717925,"2019-10-09"]
["LP Vitamins And Complementary Therapies Composite 300mm 6.0G GLF","G",6,"Live",338285,808193,338285,"2019-10-14"]
["LP Vitamins And Complementary Therapies Composite 300mm 7.0G GLF","G",7,"Live",359091,808195,359091,"2019-10-14"]
["LP Vitamins And Complementary Therapies Composite 400mm 7.0G GLF","G",7,"Live",338287,808194,338287,"2019-10-14"]
["LP Vitamins And Complementary Therapies Composite 400mm 8.0G GLF","G",8,"Live",338289,808196,338289,"2019-10-14"]
["PH LP Value End 200mm 1 1.0Y Narrow #RB","E",1,"Live",786284,786284,786284,"2019-08-18"]
["PH LP Value End 200mm 1 1.0Y Standard #RB","E",1,"Live",786288,786288,786288,"2019-08-18"]
["PH LP Value End 200mm 2 1.0Y Narrow #RB","E",1,"Live",786285,786285,786285,"2019-08-18"]
["PH LP Value End 200mm 2 1.0Y Standard #RB","E",1,"Live",786289,786289,786289,"2019-08-18"]
["PH LP Value End 200mm 3 1.0Y Narrow #RB","E",1,"Live",786286,786286,786286,"2019-08-18"]
["PH LP Value End 200mm 3 1.0Y Standard #RB","E",1,"Live",786290,786290,786290,"2019-08-18"]
["PH LP Value End 200mm 4 1.0Y Narrow #RB","E",1,"Live",786287,786287,786287,"2019-08-18"]
["PH LP Value End 200mm 4 1.0Y Standard #RB","E",1,"Live",786291,786291,786291,"2019-08-18"]
["PH LP Value End 200mm 5 1.0Y Narrow #RB","E",1,"Live",801002,801002,801002,"2019-08-18"]
["PH LP Value End 200mm 5 1.0Y Standard #RB","E",1,"Live",801003,801003,801003,"2019-08-18"]
["PH Sunglasses Alpha 1.0G Destination GF","G",1,"Live",693654,810057,693654,"2019-11-17"]
["PH Sunglasses Alpha 10.0G Destination GF","G",10,"Live",680122,810064,680122,"2019-11-17"]
["PH Sunglasses Alpha 10.0W Destination GF","W",10,"Live",680125,810063,680125,"2019-11-17"]
["PH Sunglasses Alpha 11.0G Destination GF","G",11,"Live",680114,810066,680114,"2019-11-17"]
["PH Sunglasses Alpha 11.0W Destination GF","W",11,"Live",680118,810065,680118,"2019-11-17"]
["PH Sunglasses Alpha 12.0G Destination GF","G",12,"Live",680107,810068,680107,"2019-11-17"]
["PH Sunglasses Alpha 12.0W Destination GF","W",12,"Live",680111,810067,680111,"2019-11-17"]
["PH Sunglasses Alpha 13.0G Destination GF","G",13,"Live",680098,810070,680098,"2019-11-17"]
["PH Sunglasses Alpha 13.0W Destination GF","W",13,"Live",680106,810069,680106,"2019-11-17"]
["PH Sunglasses Alpha 14.0G Destination GF","G",14,"Live",680088,810072,680088,"2019-11-17"]
["PH Sunglasses Alpha 14.0W Destination GF","W",14,"Live",680096,810071,680096,"2019-11-17"]
["PH Sunglasses Alpha 15.0G Destination GF","G",15,"Live",680075,810074,680075,"2019-11-17"]
["PH Sunglasses Alpha 15.0W Destination GF","W",15,"Live",680078,810073,680078,"2019-11-17"]
["PH Sunglasses Alpha 2.0G Destination GF","G",2,"Live",680172,810080,680172,"2019-11-17"]
["PH Sunglasses Alpha 2.0W Destination GF","W",2,"Live",680171,810079,680171,"2019-11-17"]
["PH Sunglasses Alpha 3.0G Destination GF","G",3,"Live",680170,810084,680170,"2019-11-17"]
["PH Sunglasses Alpha 3.0W Destination GF","W",3,"Live",680169,810083,680169,"2019-11-17"]
["PH Sunglasses Alpha 4.0G Destination GF","G",4,"Live",680168,810086,680168,"2019-11-17"]
["PH Sunglasses Alpha 4.0W Destination GF","W",4,"Live",680167,810085,680167,"2019-11-17"]
["PH Sunglasses Alpha 5.0G Destination GF","G",5,"Live",680166,810092,680166,"2019-11-17"]
["PH Sunglasses Alpha 5.0W Destination GF","W",5,"Live",680165,810091,680165,"2019-11-17"]
["PH Sunglasses Alpha 6.0G Destination GF","G",6,"Live",680159,810094,680159,"2019-11-17"]
["PH Sunglasses Alpha 6.0W Destination GF","W",6,"Live",680153,810093,680153,"2019-11-17"]
["PH Sunglasses Alpha 7.0G Destination GF","G",7,"Live",680141,810099,680141,"2019-11-17"]
["PH Sunglasses Alpha 7.0W Destination GF","W",7,"Live",680145,810098,680145,"2019-11-17"]
["PH Sunglasses Alpha 8.0G Destination GF","G",8,"Live",680128,810101,680128,"2019-11-17"]
["PH Sunglasses Alpha 8.0W Destination GF","W",8,"Live",680136,810100,680136,"2019-11-17"]
["PH Sunglasses Alpha 9.0G Destination GF","G",9,"Live",680126,810104,680126,"2019-11-17"]
["PH Sunglasses Alpha 9.0W Destination GF","W",9,"Live",680127,810103,680127,"2019-11-17"]
["PH Sunglasses Alpha Composite Airport 6.0G GF","G",6,"Live",558705,810113,558705,"2019-11-17"]
["Pharmacy Medicines 200mm 1.0W 2.0G LP GLF","W",3,"Live",397527,801439,397527,"2019-11-11"]
["Pharmacy Medicines 200mm 1.0W 3.0G LP GLF","W",4,"Live",397413,801436,397413,"2019-11-11"]
["Pharmacy Medicines 200mm 1.0W 4.0G LP GLF","W",5,"Live",438893,801441,438893,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0G 1.0W LP GLF","W",3,"Live",438895,801442,438895,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0G 2.0W LP GLF","W",4,"Live",439594,801449,439594,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0G 3.0W LP GLF","W",5,"Live",439575,801444,439575,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0W 1.0G LP GLF","W",3,"Live",397412,801435,397412,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0W 2.0G LP GLF","W",4,"Live",385259,801430,385259,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0W 3.0G LP GLF","W",5,"Live",397411,801434,397411,"2019-11-11"]
["Pharmacy Medicines 200mm 2.0W 4.0G LP GLF","W",6,"Live",397414,801437,397414,"2019-11-11"]
["Pharmacy Medicines 200mm 3.0G 2.0W LP GLF","W",5,"Live",440907,801453,440907,"2019-11-11"]
["Pharmacy Medicines 200mm 3.0G LP GLF","G",3,"Live",443758,801424,443758,"2019-11-11"]
["Pharmacy Medicines 200mm 3.0J LP GLF","J",3,"Live",393344,801423,393344,"2019-11-11"]
["Pharmacy Medicines 200mm 3.0W 1.0G LP GLF","W",4,"Live",395233,801433,395233,"2019-11-11"]
["Pharmacy Medicines 200mm 3.0W 2.0G LP GLF","W",5,"Live",441755,801455,441755,"2019-11-11"]
["Pharmacy Medicines 200mm 4.0G LP GLF","G",4,"Live",445307,801427,445307,"2019-11-11"]
["Pharmacy Medicines 200mm 4.0J LP GLF","J",4,"Live",384920,801425,384920,"2019-11-11"]
["Pharmacy Medicines 200mm 5.0G LP GLF","G",5,"Live",446417,801429,446417,"2019-11-11"]
["Pharmacy Medicines 200mm 5.0J LP GLF","J",5,"Live",443059,801428,443059,"2019-11-11"]
["Pharmacy Medicines Drawer line for MCO LP","G",1,"Live",394690,801471,394690,"2019-11-11"]
["Pharmacy Medicines Drawer Lines LP","G",1,"Live",382677,801420,382677,"2019-11-11"]
["Pharmacy Medicines excl Pet Meds 200mm 3.0J LP GLF","J",3,"Live",439612,801421,439612,"2019-11-11"]
["Pharmacy Medicines excl Pet Meds 200mm 5.0J LP GLF","J",5,"Live",384377,801422,384377,"2019-11-11"]
["Sunglasses Alpha 12.0G Destination GF Store 717 only","G",12,"Live",802932,802932,802932,"2019-09-14"]
["Sunglasses Alpha 300mm 6.0G SOTF Destination HB","G",6,"Live",779137,790168,779137,"2019-06-26"]
["Sunglasses Alpha Composite Airport 2.0G GF","G",2,"Live",558713,773933,558713,"2019-05-06"]
["Sunglasses Alpha Composite Airport 3.0G GF","G",3,"Live",558711,773935,558711,"2019-05-06"]
["Sunglasses Alpha Composite Airport 3.0W GF","W",3,"Live",558712,773936,558712,"2019-05-06"]
["Sunglasses Alpha Composite Airport 4.0G GF","G",4,"Live",558709,773937,558709,"2019-05-06"]
["Sunglasses Alpha Composite Airport 5.0G GF","G",5,"Live",558707,773939,558707,"2019-05-06"]
["Washing And Bathing Inc Femcare Composite LP 200mm 1.0G GLF","G",1,"Live",396603,789947,396603,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 1.0W GLF","W",1,"Live",396614,789949,396614,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 2.0W GLF","W",2,"Live",384894,789958,384894,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 2.5G GLF","G",2.5,"Live",393470,789978,393470,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 2.5W GLF","W",2.5,"Live",381660,789981,381660,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 3.0G GLF","G",3,"Live",395027,789982,395027,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 3.0W GLF","W",3,"Live",396210,789983,396210,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 3.5W GLF","W",3.5,"Live",395993,789984,395993,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 4.0G GLF","G",4,"Live",391628,789985,391628,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 4.0W GLF","W",4,"Live",391937,789986,391937,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 5.0G GLF","G",5,"Live",391941,789987,391941,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 5.0W GLF","W",5,"Live",394106,789988,394106,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 6.0G GLF","G",6,"Live",394412,789989,394412,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 6.0W GLF","W",6,"Live",395999,789990,395999,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 6.5W GLF","W",6.5,"Live",394563,789991,394563,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 7.0G GLF","G",7,"Live",394430,789993,394430,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 7.0W GLF","G",7,"Live",395025,789992,395025,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 7.5G GLF","G",7.5,"Live",396005,789994,396005,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 200mm 8.0G GLF","G",8,"Live",394642,789995,394642,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP 300mm 2.5W GLF","W",2.5,"Live",395887,789980,395887,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP RR 200mm 1.0G GLF","G",1,"Live",588363,789942,588363,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP RR 200mm 4.0G GLF","G",4,"Live",588378,789943,588378,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP RR 200mm 5.0G GLF","G",5,"Live",588371,789944,588371,"2019-08-05"]
["Washing And Bathing Inc Femcare Composite LP RR 200mm 6.0W GLF","W",6,"Live",588376,789945,588376,"2019-08-05"]
["Winter Sun Alpha Sunglasses 1.0W GF","W",1,"Live",772760,805065,772760,"2019-09-23"]
["Winter Sun Alpha Sunglasses 400mm 1.0G GF","G",1,"Live",772756,790492,772756,"2019-09-16"]
["Winter Sunglasses Alpha 300mm 1.0G SOTF Destination HB","G",1,"Live",800581,800924,800581,"2019-09-16"]
["Winter Sunglasses Alpha 300mm 2.0G Destination HB","G",2,"Live",793813,800587,793813,"2019-09-30"]

{"sheet":"Services","index":4,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"Prime Promo","index":5,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"Data","index":6,"n_rows":12,"n_cols":5,"rows_kept":12,"cut":false,"hidden":false,"merged":[]}
[]
[null,null,null,"Yes","No"]
[null,"Store Formats "]
[]
[null,"Standard"]
[null,"SOTF"]
[null,"London"]
[null,"Scotland"]
[null,"ROI"]
[null,"YLBP"]
[null,"LP"]
[null,"Services"]

{"sheet":"Test","index":7,"n_rows":4,"n_cols":5,"rows_kept":4,"cut":false,"hidden":false,"merged":[]}
[]
[]
[]
[null,null,null,null,"SOTF"]

{"sheet":"TEST 2","index":8,"n_rows":3,"n_cols":2,"rows_kept":3,"cut":false,"hidden":false,"merged":[]}
[]
[]
[null,"SOTF"]